{"id":8024,"date":"2024-07-09T09:58:41","date_gmt":"2024-07-09T15:58:41","guid":{"rendered":"http:\/\/www.archivosfutmex.com\/wordpress\/?p=8024"},"modified":"2024-07-09T09:58:43","modified_gmt":"2024-07-09T15:58:43","slug":"primera-lectura-hoy-martes-9-de-julio-2024-de-la-profecia-de-oseas-os-8-4-7-11-13","status":"publish","type":"post","link":"https:\/\/www.archivosfutmex.com\/futmex2\/archivos\/8024","title":{"rendered":"Primera Lectura Hoy Martes 9 de Julio 2024, De la Profec\u00eda de Os\u00e9as Os, 8, 4-7 11-13"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\">Os 8, 4-7. 11-13<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Esto dice el Se\u00f1or:<br>\u00abHan nombrado reyes sin contar conmigo,<br>han escogido pr\u00edncipes sin saberlo yo.<br>Con su oro y su plata se han hecho \u00eddolos,<br>para su perdici\u00f3n.<br>Tu becerro, Samaria, es repulsivo<br>y mi ira arde contra \u00e9l.<br>\u00bfHasta cu\u00e1ndo ser\u00e1n incapaces de purificarse<br>los hijos de Israel?<br>Un artesano ha hecho ese becerro, que no es Dios,<br>por eso quedar\u00e1 hecho trizas.<br><br>Siembran vientos y cosechar\u00e1n tempestades;<br>su trigo no dar\u00e1 espigas, no producir\u00e1 harina su grano,<br>y si la produce, los extranjeros se la comer\u00e1n.<br><br>Efra\u00edn ha construido multitud de altares,<br>y s\u00f3lo le han servido para pecar.<br>Aunque yo les escribiera todas mis leyes,<br>las ignorar\u00edan como si fueran de un extra\u00f1o.<br>Aunque inmolen v\u00edctimas en mi honor<br>y coman su carne, no me dan gusto,<br>pues tengo presentes sus culpas<br>y castigar\u00e9 sus pecados.<br>Por eso volver\u00e1n a la esclavitud\u00bb.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Os 8, 4-7. 11-13 Esto dice el Se\u00f1or:\u00abHan nombrado reyes sin contar conmigo,han escogido pr\u00edncipes sin saberlo yo.Con su oro y su plata se han hecho \u00eddolos,para su perdici\u00f3n.Tu becerro, Samaria, es repulsivoy mi ira arde contra \u00e9l.\u00bfHasta cu\u00e1ndo ser\u00e1n incapaces de purificarselos hijos de Israel?Un artesano ha hecho ese becerro, que no es Dios,por [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[205],"tags":[],"class_list":["post-8024","post","type-post","status-publish","format-standard","hentry","category-primera-lectura"],"_links":{"self":[{"href":"https:\/\/www.archivosfutmex.com\/futmex2\/wp-json\/wp\/v2\/posts\/8024","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.archivosfutmex.com\/futmex2\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.archivosfutmex.com\/futmex2\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.archivosfutmex.com\/futmex2\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.archivosfutmex.com\/futmex2\/wp-json\/wp\/v2\/comments?post=8024"}],"version-history":[{"count":0,"href":"https:\/\/www.archivosfutmex.com\/futmex2\/wp-json\/wp\/v2\/posts\/8024\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.archivosfutmex.com\/futmex2\/wp-json\/wp\/v2\/media?parent=8024"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.archivosfutmex.com\/futmex2\/wp-json\/wp\/v2\/categories?post=8024"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.archivosfutmex.com\/futmex2\/wp-json\/wp\/v2\/tags?post=8024"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}