{"id":10378,"date":"2024-10-02T10:11:30","date_gmt":"2024-10-02T16:11:30","guid":{"rendered":"http:\/\/www.archivosfutmex.com\/wordpress\/?p=10378"},"modified":"2024-10-02T10:11:31","modified_gmt":"2024-10-02T16:11:31","slug":"primera-lectura-del-hoy-miercoles-2-octubre-2024-del-libro-de-job-91-12-14-16","status":"publish","type":"post","link":"https:\/\/www.archivosfutmex.com\/wordpress\/archivos\/10378","title":{"rendered":"Primera Lectura del Hoy Mi\u00e9rcoles 2 Octubre 2024, Del Libro de Job 9,1-12 , 14-16"},"content":{"rendered":"\n<p>Job 9, 1-12. 14-16<\/p>\n\n\n\n<p>Job tom\u00f3 la palabra y les dijo a sus amigos:<br>\u00abS\u00e9 muy bien que el hombre<br>no puede hacer triunfar su causa contra Dios.<br>Si el hombre pretendiera entablar pleito con \u00e9l,<br>de mil cargos que Dios le hiciera, no podr\u00eda rechazar ninguno.<br>El coraz\u00f3n de Dios es sabio y su fuerza es inmensa.<br><br>\u00bfQui\u00e9n se le ha enfrentado y ha salido triunfante?<br>En un instante descuaja las monta\u00f1as<br>y sacude los montes con su c\u00f3lera;<br>\u00e9l hace retemblar toda la tierra<br>y la estremece desde sus cimientos.<br>Basta con que d\u00e9 una orden y el sol se apaga;<br>esconde cuando quiere a las estrellas;<br>\u00e9l solo despleg\u00f3 los cielos<br>y camina sobre la superficie del mar.<br>El cre\u00f3 todas las constelaciones del cielo:<br>la Osa, Ori\u00f3n, las Cabrillas y las que se ven en el sur;<br>\u00e9l hace prodigios incomprensibles, maravillas sin n\u00famero.<br><br>Cuando pasa junto a m\u00ed, no lo veo;<br>cuando se aleja de m\u00ed, no lo siento.<br>Si se apodera de algo, \u00bfqui\u00e9n se lo impedir\u00e1?<br>\u00bfQui\u00e9n podr\u00e1 decirle: &#8216;Qu\u00e9 est\u00e1s haciendo?&#8217;<br><br>Si Dios me llama a juicio,<br>\u00bfc\u00f3mo podr\u00eda yo rebatir sus acciones?<br>Aunque yo tuviera raz\u00f3n, no me quedar\u00eda otro remedio<br>que implorar su misericordia.<br>Si yo lo citara a juicio y \u00e9l compareciera,<br>no creo que atendiera a mis razones\u00bb.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Job 9, 1-12. 14-16 Job tom\u00f3 la palabra y les dijo a sus amigos:\u00abS\u00e9 muy bien que el hombreno puede hacer triunfar su causa contra Dios.Si el hombre pretendiera entablar pleito con \u00e9l,de mil cargos que Dios le hiciera, no podr\u00eda rechazar ninguno.El coraz\u00f3n de Dios es sabio y su fuerza es inmensa. \u00bfQui\u00e9n se [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[205],"tags":[],"class_list":["post-10378","post","type-post","status-publish","format-standard","hentry","category-primera-lectura"],"_links":{"self":[{"href":"https:\/\/www.archivosfutmex.com\/wordpress\/wp-json\/wp\/v2\/posts\/10378","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.archivosfutmex.com\/wordpress\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.archivosfutmex.com\/wordpress\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.archivosfutmex.com\/wordpress\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.archivosfutmex.com\/wordpress\/wp-json\/wp\/v2\/comments?post=10378"}],"version-history":[{"count":0,"href":"https:\/\/www.archivosfutmex.com\/wordpress\/wp-json\/wp\/v2\/posts\/10378\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.archivosfutmex.com\/wordpress\/wp-json\/wp\/v2\/media?parent=10378"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.archivosfutmex.com\/wordpress\/wp-json\/wp\/v2\/categories?post=10378"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.archivosfutmex.com\/wordpress\/wp-json\/wp\/v2\/tags?post=10378"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}