{"id":10731,"date":"2024-10-16T08:15:14","date_gmt":"2024-10-16T14:15:14","guid":{"rendered":"https:\/\/www.archivosfutmex.com\/wordpress\/?p=10731"},"modified":"2024-10-16T08:15:17","modified_gmt":"2024-10-16T14:15:17","slug":"oracion-colecta-hoy-miercoles-16-octubre-2024","status":"publish","type":"post","link":"https:\/\/www.archivosfutmex.com\/wordpress\/archivos\/10731","title":{"rendered":"ORACION COLECTA Hoy Mi\u00e9rcoles 16 Octubre 2024"},"content":{"rendered":"\n<p>Te rogamos , se\u00f1or, que derrames sobre nosotros el esp\u00edritu con que&nbsp; enriqueciste tan especialmente a santa Margarita Mar\u00eda , para que podamos conocer el amor de Cristo, que supera a toda ciencia , y seamos colmados de plenitud de tu gracia . Por nuestro Se\u00f1or Jesucristo\u2026.Am\u00e9n<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Te rogamos , se\u00f1or, que derrames sobre nosotros el esp\u00edritu con que&nbsp; enriqueciste tan especialmente a santa Margarita Mar\u00eda , para que podamos conocer el amor de Cristo, que supera a toda ciencia , y seamos colmados de plenitud de tu gracia . Por nuestro Se\u00f1or Jesucristo\u2026.Am\u00e9n<\/p>\n","protected":false},"author":2,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[185],"tags":[],"class_list":["post-10731","post","type-post","status-publish","format-standard","hentry","category-oracion-colecta"],"_links":{"self":[{"href":"https:\/\/www.archivosfutmex.com\/wordpress\/wp-json\/wp\/v2\/posts\/10731","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.archivosfutmex.com\/wordpress\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.archivosfutmex.com\/wordpress\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.archivosfutmex.com\/wordpress\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.archivosfutmex.com\/wordpress\/wp-json\/wp\/v2\/comments?post=10731"}],"version-history":[{"count":0,"href":"https:\/\/www.archivosfutmex.com\/wordpress\/wp-json\/wp\/v2\/posts\/10731\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.archivosfutmex.com\/wordpress\/wp-json\/wp\/v2\/media?parent=10731"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.archivosfutmex.com\/wordpress\/wp-json\/wp\/v2\/categories?post=10731"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.archivosfutmex.com\/wordpress\/wp-json\/wp\/v2\/tags?post=10731"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}