{"id":11303,"date":"2024-11-15T06:24:39","date_gmt":"2024-11-15T12:24:39","guid":{"rendered":"https:\/\/www.archivosfutmex.com\/wordpress\/?p=11303"},"modified":"2024-11-15T06:24:40","modified_gmt":"2024-11-15T12:24:40","slug":"palabras-del-santo-padre-93","status":"publish","type":"post","link":"https:\/\/www.archivosfutmex.com\/wordpress\/archivos\/11303","title":{"rendered":"Palabras del Santo Padre"},"content":{"rendered":"\n<p>Debemos estar despiertos, alertas, vigilantes. Jes\u00fas nos advierte: existe el peligro de no darse cuenta de su venida y no estar preparados para su visita. He recordado en otras ocasiones lo que dec\u00eda san Agust\u00edn: \u00abTemo al Se\u00f1or que pasa\u00bb (<em>Serm.<\/em>\u00a088.14.13), es decir, \u00a1temo que pase y no lo reconozca! De hecho, de aquellas personas de la \u00e9poca de No\u00e9, Jes\u00fas dice que com\u00edan y beb\u00edan \u00aby no se dieron cuenta hasta que vino el diluvio y los arrastr\u00f3 a todos\u00bb (v. 39). Prestemos atenci\u00f3n a esto: \u00a1no se dieron cuenta! Estaban absortos en sus cosas y no se dieron cuenta de que el diluvio se acercaba. De hecho, Jes\u00fas dice que cuando \u00c9l venga, \u00abestar\u00e1n dos en el campo: uno ser\u00e1 tomado, y el otro dejado\u00bb (v. 40).\u00a0\u00bfEn qu\u00e9 sentido? \u00bfCu\u00e1l es la diferencia? Simplemente que uno estaba vigilante, estaba esperando, capaz de discernir la presencia de Dios en la vida cotidiana; el otro, en cambio, estaba distra\u00eddo, viv\u00eda al d\u00eda y no se daba cuenta de nada. Pregunt\u00e9monos: \u00bfsoy consciente de lo que vivo, estoy alerta, estoy despierto? \u00bfEstoy tratando de reconocer la presencia de Dios en las situaciones cotidianas, o estoy distra\u00eddo y un poco abrumado por las cosas? Si no somos conscientes de su venida hoy, tampoco estaremos preparados cuando venga al final de los tiempos. . (\u00c1ngelu<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Debemos estar despiertos, alertas, vigilantes. Jes\u00fas nos advierte: existe el peligro de no darse cuenta de su venida y no estar preparados para su visita. He recordado en otras ocasiones lo que dec\u00eda san Agust\u00edn: \u00abTemo al Se\u00f1or que pasa\u00bb (Serm.\u00a088.14.13), es decir, \u00a1temo que pase y no lo reconozca! De hecho, de aquellas personas [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[229],"tags":[],"class_list":["post-11303","post","type-post","status-publish","format-standard","hentry","category-palabras-del-santo-padre"],"_links":{"self":[{"href":"https:\/\/www.archivosfutmex.com\/wordpress\/wp-json\/wp\/v2\/posts\/11303","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.archivosfutmex.com\/wordpress\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.archivosfutmex.com\/wordpress\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.archivosfutmex.com\/wordpress\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.archivosfutmex.com\/wordpress\/wp-json\/wp\/v2\/comments?post=11303"}],"version-history":[{"count":0,"href":"https:\/\/www.archivosfutmex.com\/wordpress\/wp-json\/wp\/v2\/posts\/11303\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.archivosfutmex.com\/wordpress\/wp-json\/wp\/v2\/media?parent=11303"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.archivosfutmex.com\/wordpress\/wp-json\/wp\/v2\/categories?post=11303"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.archivosfutmex.com\/wordpress\/wp-json\/wp\/v2\/tags?post=11303"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}