{"id":11358,"date":"2024-11-21T20:17:00","date_gmt":"2024-11-22T02:17:00","guid":{"rendered":"https:\/\/www.archivosfutmex.com\/wordpress\/?p=11358"},"modified":"2024-11-21T20:17:00","modified_gmt":"2024-11-22T02:17:00","slug":"oracion-colecta-manana-hoy-viernes-22-noviembre-2024","status":"publish","type":"post","link":"https:\/\/www.archivosfutmex.com\/wordpress\/archivos\/11358","title":{"rendered":"ORACION COLECTA Ma\u00f1ana (Hoy) Viernes 22 Noviembre 2024"},"content":{"rendered":"\n<p>Dios Nuestro , que nos alegras cada a\u00f1o con la celebraci\u00f3n de Santa Cecilia , te suplicamos que , lo que devotamente se nos ha trasmitido sobre ella , nos sirva de ejemplo para imitarla , y proclamemos las Maravillas de Cristo, tu Hijo, reflejadas en la vida de tus santos . El, que vive y reina contigo\u2026.Am\u00e9n<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Dios Nuestro , que nos alegras cada a\u00f1o con la celebraci\u00f3n de Santa Cecilia , te suplicamos que , lo que devotamente se nos ha trasmitido sobre ella , nos sirva de ejemplo para imitarla , y proclamemos las Maravillas de Cristo, tu Hijo, reflejadas en la vida de tus santos . El, que vive [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[185],"tags":[],"class_list":["post-11358","post","type-post","status-publish","format-standard","hentry","category-oracion-colecta"],"_links":{"self":[{"href":"https:\/\/www.archivosfutmex.com\/wordpress\/wp-json\/wp\/v2\/posts\/11358","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.archivosfutmex.com\/wordpress\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.archivosfutmex.com\/wordpress\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.archivosfutmex.com\/wordpress\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.archivosfutmex.com\/wordpress\/wp-json\/wp\/v2\/comments?post=11358"}],"version-history":[{"count":0,"href":"https:\/\/www.archivosfutmex.com\/wordpress\/wp-json\/wp\/v2\/posts\/11358\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.archivosfutmex.com\/wordpress\/wp-json\/wp\/v2\/media?parent=11358"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.archivosfutmex.com\/wordpress\/wp-json\/wp\/v2\/categories?post=11358"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.archivosfutmex.com\/wordpress\/wp-json\/wp\/v2\/tags?post=11358"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}