{"id":12848,"date":"2025-03-11T07:15:22","date_gmt":"2025-03-11T13:15:22","guid":{"rendered":"http:\/\/www.archivosfutmex.com\/wordpress\/?p=12848"},"modified":"2025-03-11T07:15:23","modified_gmt":"2025-03-11T13:15:23","slug":"oracion-colecta-hoy-martes-11-marzo-2025","status":"publish","type":"post","link":"https:\/\/www.archivosfutmex.com\/wordpress\/archivos\/12848","title":{"rendered":"ORACION COLECTA Hoy Martes 11 Marzo 2025"},"content":{"rendered":"\n<p>Mira, Se\u00f1or, a tu Familia y concede que mientras afligimos nuestro cuerpo con la penitencia , nuestro esp\u00edritu se vea iluminado por el deseo de estar cerca de ti. Por Nuestro Se\u00f1or Jesucristo , tu Hijo, que vive y reina contigo en la unidad del Espiritu Santo y es Dios por los Siglos de los Siglos Am\u00e9n\u2026..<br>\u00a0<br>\u00a0<br>\u00a0<br>\u00a0<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Mira, Se\u00f1or, a tu Familia y concede que mientras afligimos nuestro cuerpo con la penitencia , nuestro esp\u00edritu se vea iluminado por el deseo de estar cerca de ti. Por Nuestro Se\u00f1or Jesucristo , tu Hijo, que vive y reina contigo en la unidad del Espiritu Santo y es Dios por los Siglos de los [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[185],"tags":[],"class_list":["post-12848","post","type-post","status-publish","format-standard","hentry","category-oracion-colecta"],"_links":{"self":[{"href":"https:\/\/www.archivosfutmex.com\/wordpress\/wp-json\/wp\/v2\/posts\/12848","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.archivosfutmex.com\/wordpress\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.archivosfutmex.com\/wordpress\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.archivosfutmex.com\/wordpress\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.archivosfutmex.com\/wordpress\/wp-json\/wp\/v2\/comments?post=12848"}],"version-history":[{"count":0,"href":"https:\/\/www.archivosfutmex.com\/wordpress\/wp-json\/wp\/v2\/posts\/12848\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.archivosfutmex.com\/wordpress\/wp-json\/wp\/v2\/media?parent=12848"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.archivosfutmex.com\/wordpress\/wp-json\/wp\/v2\/categories?post=12848"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.archivosfutmex.com\/wordpress\/wp-json\/wp\/v2\/tags?post=12848"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}