{"id":12850,"date":"2025-03-11T23:44:32","date_gmt":"2025-03-12T05:44:32","guid":{"rendered":"http:\/\/www.archivosfutmex.com\/wordpress\/?p=12850"},"modified":"2025-03-11T23:44:33","modified_gmt":"2025-03-12T05:44:33","slug":"oracion-colecta-hoy-miercoles-12-de-marzo-2025","status":"publish","type":"post","link":"https:\/\/www.archivosfutmex.com\/wordpress\/archivos\/12850","title":{"rendered":"ORACION COLECTA Hoy Mi\u00e9rcoles 12 de Marzo 2025"},"content":{"rendered":"\n<p>Mira con Bondad , Se\u00f1or , la devota entrega de tu pueblo y ya que con privaciones se empe\u00f1a en dominar su cuerpo, haz que con el fruto de sus buenas obras se fortalezca su alma: por nuestro Se\u00f1or Jesucristo, tu Hijo, que vive y reina contigo en la unidad del esp\u00edritu Santo y es Dios por los siglos de los siglos\u2026.Am\u00e9n\u2026<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Mira con Bondad , Se\u00f1or , la devota entrega de tu pueblo y ya que con privaciones se empe\u00f1a en dominar su cuerpo, haz que con el fruto de sus buenas obras se fortalezca su alma: por nuestro Se\u00f1or Jesucristo, tu Hijo, que vive y reina contigo en la unidad del esp\u00edritu Santo y es [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[185],"tags":[],"class_list":["post-12850","post","type-post","status-publish","format-standard","hentry","category-oracion-colecta"],"_links":{"self":[{"href":"https:\/\/www.archivosfutmex.com\/wordpress\/wp-json\/wp\/v2\/posts\/12850","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.archivosfutmex.com\/wordpress\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.archivosfutmex.com\/wordpress\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.archivosfutmex.com\/wordpress\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.archivosfutmex.com\/wordpress\/wp-json\/wp\/v2\/comments?post=12850"}],"version-history":[{"count":0,"href":"https:\/\/www.archivosfutmex.com\/wordpress\/wp-json\/wp\/v2\/posts\/12850\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.archivosfutmex.com\/wordpress\/wp-json\/wp\/v2\/media?parent=12850"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.archivosfutmex.com\/wordpress\/wp-json\/wp\/v2\/categories?post=12850"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.archivosfutmex.com\/wordpress\/wp-json\/wp\/v2\/tags?post=12850"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}