{"id":14077,"date":"2025-06-25T10:27:27","date_gmt":"2025-06-25T16:27:27","guid":{"rendered":"http:\/\/www.archivosfutmex.com\/wordpress\/?p=14077"},"modified":"2025-06-25T10:27:28","modified_gmt":"2025-06-25T16:27:28","slug":"wydad-ac-social-media-2025-facebook-instagram-twitterx-youtube-tik-tok-updated-actualizado-wednesday-june-25th-2025","status":"publish","type":"post","link":"https:\/\/www.archivosfutmex.com\/wordpress\/archivos\/14077","title":{"rendered":"Wydad AC Social Media 2025 (Facebook, Instagram, Twitter(X), Youtube, Tik Tok ) Updated \/ Actualizado: Wednesday June 25th 2025"},"content":{"rendered":"\n<p>e-mail: brasilmemo42@gmail.com<\/p>\n\n\n\n<p>Wydad AC Social Media 2025<\/p>\n\n\n\n<p>Updated \/ Actualizado : Wednesday June 25<sup>th<\/sup> 2025<\/p>\n\n\n\n<p>FACEBOOK: 3.2 Millones Followers \/ 2.5 Millones Likes<\/p>\n\n\n\n<p>INSTAGRAM: 2.3 Millones Followers\/ 8 881 Publicaciones<\/p>\n\n\n\n<p>TWITTER (X): 544.9 Miles Followers\/ 12.3 Miles Posts<\/p>\n\n\n\n<p>YOUTUBE: 264 Miles Suscriptores \/ 720 Videos<\/p>\n\n\n\n<p>TIK TOK: &nbsp;369.6 Miles Followers \/ 3.2 Millones<\/p>\n\n\n\n<p>TOTAL WYDAD AC : 6.67 Millones Followers<\/p>\n","protected":false},"excerpt":{"rendered":"<p>e-mail: brasilmemo42@gmail.com Wydad AC Social Media 2025 Updated \/ Actualizado : Wednesday June 25th 2025 FACEBOOK: 3.2 Millones Followers \/ 2.5 Millones Likes INSTAGRAM: 2.3 Millones Followers\/ 8 881 Publicaciones TWITTER (X): 544.9 Miles Followers\/ 12.3 Miles Posts YOUTUBE: 264 Miles Suscriptores \/ 720 Videos TIK TOK: &nbsp;369.6 Miles Followers \/ 3.2 Millones TOTAL WYDAD [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[487],"tags":[],"class_list":["post-14077","post","type-post","status-publish","format-standard","hentry","category-wydad-ac-social-media-2025-facebook-instagram-twitterx-youtube-tik-tok"],"_links":{"self":[{"href":"https:\/\/www.archivosfutmex.com\/wordpress\/wp-json\/wp\/v2\/posts\/14077","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.archivosfutmex.com\/wordpress\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.archivosfutmex.com\/wordpress\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.archivosfutmex.com\/wordpress\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.archivosfutmex.com\/wordpress\/wp-json\/wp\/v2\/comments?post=14077"}],"version-history":[{"count":0,"href":"https:\/\/www.archivosfutmex.com\/wordpress\/wp-json\/wp\/v2\/posts\/14077\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.archivosfutmex.com\/wordpress\/wp-json\/wp\/v2\/media?parent=14077"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.archivosfutmex.com\/wordpress\/wp-json\/wp\/v2\/categories?post=14077"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.archivosfutmex.com\/wordpress\/wp-json\/wp\/v2\/tags?post=14077"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}