{"id":14283,"date":"2025-07-23T08:34:44","date_gmt":"2025-07-23T14:34:44","guid":{"rendered":"http:\/\/www.archivosfutmex.com\/wordpress\/?p=14283"},"modified":"2025-07-23T08:34:45","modified_gmt":"2025-07-23T14:34:45","slug":"lectura-de-hoy-miercoles-23-julio-2023-del-libro-del-exodo-16-1-5-9-15","status":"publish","type":"post","link":"https:\/\/www.archivosfutmex.com\/wordpress\/archivos\/14283","title":{"rendered":"Lectura de Hoy Mi\u00e9rcoles 23 Julio 2023, Del Libro del \u00c9xodo , 16, 1-5, 9-15"},"content":{"rendered":"\n<p>\u00c9xodo 16, 1-5. 9-15<\/p>\n\n\n\n<p>El d\u00eda quince del segundo mes, despu\u00e9s de salir de Egipto, toda la comunidad de Israel parti\u00f3 de Elim y lleg\u00f3 al desierto de Sin, entre Elim y el Sina\u00ed.&nbsp;<\/p>\n\n\n\n<p>Toda la comunidad de los hijos de Israel murmur\u00f3 contra Mois\u00e9s y Aar\u00f3n en el desierto, diciendo: \u201cOjal\u00e1 hubi\u00e9ramos muerto a manos del Se\u00f1or en Egipto, cuando nos sent\u00e1bamos junto a las ollas de carne y com\u00edamos pan hasta saciarnos. Ustedes nos han tra\u00eddo a este desierto para matar de hambre a toda esta multitud\u201d.&nbsp;<\/p>\n\n\n\n<p>Entonces dijo el Se\u00f1or a Mois\u00e9s: \u201cVoy a hacer que llueva pan del cielo. Que el pueblo salga a recoger cada d\u00eda lo que necesita, pues quiero probar si guarda mi ley o no. El d\u00eda sexto recoger\u00e1n el doble de lo que suelen recoger cada d\u00eda y guardar\u00e1n una parte para el d\u00eda siguiente\u201d.&nbsp;<\/p>\n\n\n\n<p>Mois\u00e9s le dijo a Aar\u00f3n: \u201cDi a la comunidad de los israelitas: \u2018Vengan ante la presencia del Se\u00f1or, porque \u00e9l ha escuchado las quejas de ustedes\u2019 \u201d. Mientras Aar\u00f3n hablaba a toda la asamblea, ellos se volvieron hacia el desierto y vieron la gloria del Se\u00f1or, que aparec\u00eda en una nube.&nbsp;<\/p>\n\n\n\n<p>El Se\u00f1or le dijo a Mois\u00e9s: \u201cHe o\u00eddo las murmuraciones de los hijos de Israel. Diles de parte m\u00eda: \u2018Por la tarde comer\u00e1n carne y por la ma\u00f1ana se hartar\u00e1n de pan, para que sepan que yo soy el Se\u00f1or, su Dios\u2019 \u201d.&nbsp;<\/p>\n\n\n\n<p>Aquella misma tarde, una bandada de codornices cubri\u00f3 el campamento. A la ma\u00f1ana siguiente hab\u00eda en torno a \u00e9l una capa de roc\u00edo que, al evaporarse, dej\u00f3 el suelo cubierto con una especie de polvo blanco, semejante a la escarcha. Al ver eso, los israelitas se dijeron unos a otros: \u201c\u00bfQu\u00e9 es esto?\u201d, pues no sab\u00edan lo que era. Mois\u00e9s les dijo: \u201cEste es el pan que el Se\u00f1or les da por alimento\u201d.&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>\u00c9xodo 16, 1-5. 9-15 El d\u00eda quince del segundo mes, despu\u00e9s de salir de Egipto, toda la comunidad de Israel parti\u00f3 de Elim y lleg\u00f3 al desierto de Sin, entre Elim y el Sina\u00ed.&nbsp; Toda la comunidad de los hijos de Israel murmur\u00f3 contra Mois\u00e9s y Aar\u00f3n en el desierto, diciendo: \u201cOjal\u00e1 hubi\u00e9ramos muerto a [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[205],"tags":[],"class_list":["post-14283","post","type-post","status-publish","format-standard","hentry","category-primera-lectura"],"_links":{"self":[{"href":"https:\/\/www.archivosfutmex.com\/wordpress\/wp-json\/wp\/v2\/posts\/14283","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.archivosfutmex.com\/wordpress\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.archivosfutmex.com\/wordpress\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.archivosfutmex.com\/wordpress\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.archivosfutmex.com\/wordpress\/wp-json\/wp\/v2\/comments?post=14283"}],"version-history":[{"count":0,"href":"https:\/\/www.archivosfutmex.com\/wordpress\/wp-json\/wp\/v2\/posts\/14283\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.archivosfutmex.com\/wordpress\/wp-json\/wp\/v2\/media?parent=14283"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.archivosfutmex.com\/wordpress\/wp-json\/wp\/v2\/categories?post=14283"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.archivosfutmex.com\/wordpress\/wp-json\/wp\/v2\/tags?post=14283"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}