{"id":19594,"date":"2026-03-22T09:29:47","date_gmt":"2026-03-22T15:29:47","guid":{"rendered":"https:\/\/www.archivosfutmex.com\/wordpress\/?p=19594"},"modified":"2026-03-22T09:29:48","modified_gmt":"2026-03-22T15:29:48","slug":"palabras-del-santo-padre-215","status":"publish","type":"post","link":"https:\/\/www.archivosfutmex.com\/wordpress\/archivos\/19594","title":{"rendered":"PALABRAS DEL SANTO PADRE"},"content":{"rendered":"\n<p>El Evangelio de este quinto domingo de Cuaresma es el de la Resurrecci\u00f3n de L\u00e1zaro (&#8230;)\u00a0Jes\u00fas podr\u00eda haber evitado la muerte de su amigo L\u00e1zaro, pero quiso hacer suyo nuestro dolor por la muerte de nuestros seres queridos y, sobre todo, quiso mostrar el dominio de Dios sobre la muerte. En este pasaje del Evangelio vemos que la fe del hombre y la omnipotencia de Dios, el amor de Dios, se buscan y, finalmente, se encuentran. Es como un doble camino: la fe del hombre y la omnipotencia del amor de Dios se buscan y finalmente se encuentran. Lo vemos en el grito de Marta y Mar\u00eda y todos nosotros con ellas: \u201c\u00a1Si hubieras estado aqu\u00ed!&#8230;\u201d. Y la respuesta de Dios no es un discurso, no, la respuesta de Dios al problema de la muerte es Jes\u00fas: \u201cYo soy la resurrecci\u00f3n y la vida&#8230; \u00a1Tened fe! En medio del llanto seguid teniendo fe, aunque la muerte parezca haber vencido. \u00a1Quitad la piedra de vuestro coraz\u00f3n! Que la Palabra de Dios devuelva la vida all\u00ed donde hay muerte\u201d. Tambi\u00e9n hoy nos repite Jes\u00fas: \u201cQuitad la piedra\u201d. (&#8230;)\u00a0Cristo vive, y quien lo acoge y se adhiere a \u00c9l entra en contacto con la vida. (Papa Francisco,\u00a0\u00c1ngelus 29 de marzo de 2020)<\/p>\n","protected":false},"excerpt":{"rendered":"<p>El Evangelio de este quinto domingo de Cuaresma es el de la Resurrecci\u00f3n de L\u00e1zaro (&#8230;)\u00a0Jes\u00fas podr\u00eda haber evitado la muerte de su amigo L\u00e1zaro, pero quiso hacer suyo nuestro dolor por la muerte de nuestros seres queridos y, sobre todo, quiso mostrar el dominio de Dios sobre la muerte. En este pasaje del Evangelio [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[229],"tags":[],"class_list":["post-19594","post","type-post","status-publish","format-standard","hentry","category-palabras-del-santo-padre"],"_links":{"self":[{"href":"https:\/\/www.archivosfutmex.com\/wordpress\/wp-json\/wp\/v2\/posts\/19594","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.archivosfutmex.com\/wordpress\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.archivosfutmex.com\/wordpress\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.archivosfutmex.com\/wordpress\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.archivosfutmex.com\/wordpress\/wp-json\/wp\/v2\/comments?post=19594"}],"version-history":[{"count":1,"href":"https:\/\/www.archivosfutmex.com\/wordpress\/wp-json\/wp\/v2\/posts\/19594\/revisions"}],"predecessor-version":[{"id":19595,"href":"https:\/\/www.archivosfutmex.com\/wordpress\/wp-json\/wp\/v2\/posts\/19594\/revisions\/19595"}],"wp:attachment":[{"href":"https:\/\/www.archivosfutmex.com\/wordpress\/wp-json\/wp\/v2\/media?parent=19594"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.archivosfutmex.com\/wordpress\/wp-json\/wp\/v2\/categories?post=19594"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.archivosfutmex.com\/wordpress\/wp-json\/wp\/v2\/tags?post=19594"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}