{"id":19658,"date":"2026-03-23T21:33:46","date_gmt":"2026-03-24T03:33:46","guid":{"rendered":"https:\/\/www.archivosfutmex.com\/wordpress\/?p=19658"},"modified":"2026-03-23T21:33:47","modified_gmt":"2026-03-24T03:33:47","slug":"lectura-de-hoy-martes-24-marzo-2026-de-la-profecia-de-daniel-13-41-62","status":"publish","type":"post","link":"https:\/\/www.archivosfutmex.com\/wordpress\/archivos\/19658","title":{"rendered":"Lectura de Hoy Martes 24 Marzo 2026 , De la Profec\u00eda de Daniel , 13, 41-62"},"content":{"rendered":"\n<p>Daniel&nbsp;13, 41-62<\/p>\n\n\n\n<p>En aquel tiempo, la asamblea crey\u00f3 a los ancianos que hab\u00edan calumniado a Susana y la conden\u00f3 a muerte. Entonces Susana, dando fuertes voces exclam\u00f3: \u201cDios eterno, que conoces los secretos y lo sabes todo antes de que suceda, t\u00fa sabes que \u00e9stos me han levantado un falso testimonio. Y voy a morir sin haber hecho nada de lo que su maldad ha tramado contra m\u00ed\u201d. El Se\u00f1or escuch\u00f3 su voz. Cuando llevaban a Susana al sitio de la ejecuci\u00f3n, el Se\u00f1or hizo sentir a un muchacho, llamado Daniel, el santo impulso de ponerse a gritar: \u201cYo no soy responsable de la sangre de esta mujer\u201d.<\/p>\n\n\n\n<p>Todo el pueblo se volvi\u00f3 a mirarlo y le preguntaron: \u201c\u00bfQu\u00e9 es lo que est\u00e1s diciendo?\u201d Entonces Daniel, de pie en medio de ellos, les respondi\u00f3: \u201cIsraelitas, \u00bfc\u00f3mo pueden ser tan ciegos? Han condenado a muerte a una hija de Israel, sin haber investigado y puesto en claro la verdad. Vuelvan al tribunal, porque \u00e9sos le han levantado un falso testimonio\u201d.<\/p>\n\n\n\n<p>Todo el pueblo regres\u00f3 de prisa y los ancianos dijeron a Daniel: \u201cVen a sentarte en medio de nosotros y dinos lo que piensas, puesto que Dios mismo te ha dado la madurez de un anciano\u201d. Daniel les dijo entonces: \u201cSeparen a los acusadores, lejos el uno del otro, y yo los voy a interrogar\u201d.<\/p>\n\n\n\n<p>Una vez separados, Daniel mand\u00f3 llamar a uno de ellos y le dijo: \u201cViejo en a\u00f1os y en cr\u00edmenes, ahora van a quedar al descubierto tus pecados anteriores, cuando injustamente condenabas a los inocentes y absolv\u00edas a los culpables, contra el mandamiento del Se\u00f1or: No matar\u00e1s al que es justo e inocente. Ahora bien, si es cierto que los viste, dime debajo de qu\u00e9 \u00e1rbol estaban juntos\u201d. \u00c9l respondi\u00f3: \u201cDebajo de una acacia\u201d. Daniel le dijo: \u201cMuy bien. Tu mentira te va a costar la vida, pues ya el \u00e1ngel ha recibido de Dios tu sentencia y te va a partir por la mitad\u201d. Daniel les dijo que se lo llevaran, mand\u00f3 traer al otro y le dijo: \u201cRaza de Cana\u00e1n y no de Jud\u00e1, la belleza te sedujo y la pasi\u00f3n te pervirti\u00f3 el coraz\u00f3n. Lo mismo hac\u00edan ustedes con las mujeres de Israel, y ellas, por miedo, se entregaban a ustedes. Pero una mujer de Jud\u00e1 no ha podido soportar la maldad de ustedes. Ahora dime, \u00bfbajo qu\u00e9 \u00e1rbol los sorprendiste abrazados?\u201d \u00c9l contest\u00f3: \u201cDebajo de una encina\u201d. Replic\u00f3 Daniel: \u201cTambi\u00e9n a ti tu mentira te costar\u00e1 la vida. El \u00e1ngel del Se\u00f1or aguarda ya con la espada en la mano, para partirte por la mitad. As\u00ed acabar\u00e1 con ustedes\u201d.<\/p>\n\n\n\n<p>Entonces toda la asamblea levant\u00f3 la voz y bendijo a Dios, que salva a los que esperan en \u00e9l. Se alzaron contra los dos viejos, a quienes, con palabras de ellos mismos, Daniel hab\u00eda convencido de falso testimonio, y les aplicaron la pena que ellos mismos hab\u00edan maquinado contra su pr\u00f3jimo. Para cumplir con la ley de Mois\u00e9s, los mataron, y aquel d\u00eda se salv\u00f3 una vida inocente.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Daniel&nbsp;13, 41-62 En aquel tiempo, la asamblea crey\u00f3 a los ancianos que hab\u00edan calumniado a Susana y la conden\u00f3 a muerte. Entonces Susana, dando fuertes voces exclam\u00f3: \u201cDios eterno, que conoces los secretos y lo sabes todo antes de que suceda, t\u00fa sabes que \u00e9stos me han levantado un falso testimonio. Y voy a morir [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[205],"tags":[],"class_list":["post-19658","post","type-post","status-publish","format-standard","hentry","category-primera-lectura"],"_links":{"self":[{"href":"https:\/\/www.archivosfutmex.com\/wordpress\/wp-json\/wp\/v2\/posts\/19658","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.archivosfutmex.com\/wordpress\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.archivosfutmex.com\/wordpress\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.archivosfutmex.com\/wordpress\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.archivosfutmex.com\/wordpress\/wp-json\/wp\/v2\/comments?post=19658"}],"version-history":[{"count":1,"href":"https:\/\/www.archivosfutmex.com\/wordpress\/wp-json\/wp\/v2\/posts\/19658\/revisions"}],"predecessor-version":[{"id":19659,"href":"https:\/\/www.archivosfutmex.com\/wordpress\/wp-json\/wp\/v2\/posts\/19658\/revisions\/19659"}],"wp:attachment":[{"href":"https:\/\/www.archivosfutmex.com\/wordpress\/wp-json\/wp\/v2\/media?parent=19658"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.archivosfutmex.com\/wordpress\/wp-json\/wp\/v2\/categories?post=19658"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.archivosfutmex.com\/wordpress\/wp-json\/wp\/v2\/tags?post=19658"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}