{"id":19660,"date":"2026-03-23T22:03:22","date_gmt":"2026-03-24T04:03:22","guid":{"rendered":"https:\/\/www.archivosfutmex.com\/wordpress\/?p=19660"},"modified":"2026-03-23T22:03:23","modified_gmt":"2026-03-24T04:03:23","slug":"el-santo-evangelio-de-hoy-del-evangelio-segun-san-juan-jn-8-1-11","status":"publish","type":"post","link":"https:\/\/www.archivosfutmex.com\/wordpress\/archivos\/19660","title":{"rendered":"El Santo Evangelio de Hoy , Del Evangelio seg\u00fan San Juan Jn, 8. 1-11"},"content":{"rendered":"\n<p>Juan 8, 1-11<\/p>\n\n\n\n<p>En aquel tiempo, Jes\u00fas se retir\u00f3 al monte de los Olivos y al amanecer se present\u00f3 de nuevo en el templo, donde la multitud se le acercaba; y \u00e9l, sentado entre ellos, les ense\u00f1aba.<\/p>\n\n\n\n<p>Entonces los escribas y fariseos le llevaron a una mujer sorprendida en adulterio, y poni\u00e9ndola frente a \u00e9l, le dijeron: \u201cMaestro, esta mujer ha sido sorprendida en flagrante adulterio. Mois\u00e9s nos manda en la ley apedrear a estas mujeres. \u00bfT\u00fa qu\u00e9 dices?\u201d<\/p>\n\n\n\n<p>Le preguntaban esto para ponerle una trampa y poder acusarlo. Pero Jes\u00fas se agach\u00f3 y se puso a escribir en el suelo con el dedo. Como insist\u00edan en su pregunta, se incorpor\u00f3 y les dijo: \u201cAquel de ustedes que no tenga pecado, que le tire la primera piedra\u201d. Se volvi\u00f3 a agachar y sigui\u00f3 escribiendo en el suelo.<\/p>\n\n\n\n<p>Al o\u00edr aquellas palabras, los acusadores comenzaron a escabullirse uno tras otro, empezando por los m\u00e1s viejos, hasta que dejaron solos a Jes\u00fas y a la mujer, que estaba de pie, junto a \u00e9l.<\/p>\n\n\n\n<p>Entonces Jes\u00fas se enderez\u00f3 y le pregunt\u00f3: \u201cMujer, \u00bfd\u00f3nde est\u00e1n los que te acusaban? \u00bfNadie te ha condenado?\u201d Ella le contest\u00f3: \u201cNadie, Se\u00f1or\u201d. Y Jes\u00fas le dijo: \u201cTampoco yo te condeno. Vete y ya no vuelvas a pecar\u201d.<\/p>\n\n\n\n<p><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Juan 8, 1-11 En aquel tiempo, Jes\u00fas se retir\u00f3 al monte de los Olivos y al amanecer se present\u00f3 de nuevo en el templo, donde la multitud se le acercaba; y \u00e9l, sentado entre ellos, les ense\u00f1aba. Entonces los escribas y fariseos le llevaron a una mujer sorprendida en adulterio, y poni\u00e9ndola frente a \u00e9l, [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[165],"tags":[],"class_list":["post-19660","post","type-post","status-publish","format-standard","hentry","category-evangelio-de-hoy"],"_links":{"self":[{"href":"https:\/\/www.archivosfutmex.com\/wordpress\/wp-json\/wp\/v2\/posts\/19660","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.archivosfutmex.com\/wordpress\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.archivosfutmex.com\/wordpress\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.archivosfutmex.com\/wordpress\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.archivosfutmex.com\/wordpress\/wp-json\/wp\/v2\/comments?post=19660"}],"version-history":[{"count":1,"href":"https:\/\/www.archivosfutmex.com\/wordpress\/wp-json\/wp\/v2\/posts\/19660\/revisions"}],"predecessor-version":[{"id":19661,"href":"https:\/\/www.archivosfutmex.com\/wordpress\/wp-json\/wp\/v2\/posts\/19660\/revisions\/19661"}],"wp:attachment":[{"href":"https:\/\/www.archivosfutmex.com\/wordpress\/wp-json\/wp\/v2\/media?parent=19660"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.archivosfutmex.com\/wordpress\/wp-json\/wp\/v2\/categories?post=19660"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.archivosfutmex.com\/wordpress\/wp-json\/wp\/v2\/tags?post=19660"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}