{"id":5569,"date":"2024-05-07T07:47:55","date_gmt":"2024-05-07T13:47:55","guid":{"rendered":"http:\/\/www.archivosfutmex.com\/wordpress\/?p=5569"},"modified":"2024-05-07T07:47:55","modified_gmt":"2024-05-07T13:47:55","slug":"primera-lectura-del-segun-los-hechos-de-los-apostoles-hch-16-22-34","status":"publish","type":"post","link":"https:\/\/www.archivosfutmex.com\/wordpress\/archivos\/5569","title":{"rendered":"Primera Lectura del seg\u00fan Los Hechos de los Ap\u00f3stoles Hch, 16, 22 &#8211; 34"},"content":{"rendered":"\n<p>Lectura del libro de los Hechos de los ap\u00f3stoles<\/p>\n\n\n\n<p>Hch 16, 22-34<\/p>\n\n\n\n<p>En aquellos d\u00edas, la gente de la ciudad de Filipos se alborot\u00f3 contra Pablo y Silas, y los magistrados ordenaron que los desnudaran y los azotaran. Despu\u00e9s de azotarlos mucho, los metieron en la c\u00e1rcel y le ordenaron al carcelero que los vigilara bien. Siguiendo esta orden, \u00e9l los meti\u00f3 en el calabozo de m\u00e1s adentro y les asegur\u00f3 los pies en el cepo.<br><br>A eso de la medianoche, Pablo y Silas estaban en oraci\u00f3n, cantando himnos al Se\u00f1or, y los otros presos los escuchaban. De pronto sobrevino un temblor tan violento, que se sacudieron los cimientos de la c\u00e1rcel, las puertas se abrieron de golpe y a todos se les soltaron las cadenas.<br><br>El carcelero se despert\u00f3, y al ver las puertas de la c\u00e1rcel abiertas de par en par, pens\u00f3 que los presos se hab\u00edan fugado y sac\u00f3 su espada para matarse. Pero entonces Pablo le grit\u00f3: \u00abNo te hagas ning\u00fan da\u00f1o; aqu\u00ed estamos todos\u00bb. El carcelero pidi\u00f3 una l\u00e1mpara, se precipit\u00f3 hacia dentro, y temblando, se arroj\u00f3 a los pies de Pablo y Silas. Despu\u00e9s los sac\u00f3 de all\u00ed y les pregunt\u00f3: \u00ab\u00bfQu\u00e9 debo hacer para salvarme?\u00bb Ellos le contestaron: \u00abCree en el Se\u00f1or Jes\u00fas y te salvar\u00e1s, t\u00fa y tu familia\u00bb. Y les explicaron la palabra del Se\u00f1or a \u00e9l y a todos los de su casa.<br><br>El carcelero se los llev\u00f3 aparte, y en aquella misma hora de la noche les lav\u00f3 las heridas y enseguida se bautiz\u00f3 \u00e9l con todos los suyos. Despu\u00e9s los invit\u00f3 a su casa, les prepar\u00f3 la mesa y celebraron una fiesta familiar por haber cre\u00eddo en Dios.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Lectura del libro de los Hechos de los ap\u00f3stoles Hch 16, 22-34 En aquellos d\u00edas, la gente de la ciudad de Filipos se alborot\u00f3 contra Pablo y Silas, y los magistrados ordenaron que los desnudaran y los azotaran. Despu\u00e9s de azotarlos mucho, los metieron en la c\u00e1rcel y le ordenaron al carcelero que los vigilara [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[205],"tags":[],"class_list":["post-5569","post","type-post","status-publish","format-standard","hentry","category-primera-lectura"],"_links":{"self":[{"href":"https:\/\/www.archivosfutmex.com\/wordpress\/wp-json\/wp\/v2\/posts\/5569","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.archivosfutmex.com\/wordpress\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.archivosfutmex.com\/wordpress\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.archivosfutmex.com\/wordpress\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.archivosfutmex.com\/wordpress\/wp-json\/wp\/v2\/comments?post=5569"}],"version-history":[{"count":0,"href":"https:\/\/www.archivosfutmex.com\/wordpress\/wp-json\/wp\/v2\/posts\/5569\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.archivosfutmex.com\/wordpress\/wp-json\/wp\/v2\/media?parent=5569"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.archivosfutmex.com\/wordpress\/wp-json\/wp\/v2\/categories?post=5569"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.archivosfutmex.com\/wordpress\/wp-json\/wp\/v2\/tags?post=5569"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}